{"id":199430,"date":"2021-03-01T14:05:09","date_gmt":"2021-03-01T13:05:09","guid":{"rendered":"https:\/\/freekids.pl\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/"},"modified":"2021-03-01T14:05:09","modified_gmt":"2021-03-01T13:05:09","slug":"fitness-im-freien-als-bereicherung-des-sportunterrichts","status":"publish","type":"post","link":"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/","title":{"rendered":"Fitness im Freien als Bereicherung des Sportunterrichts"},"content":{"rendered":"<div class=\"section standard\">\n<div class=\"row\">\n<div class=\"column\" style=\"width: 100%;\">\n<div class=\"content\">\n<p style=\"text-align: center;\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10282\" src=\"https:\/\/freekids.pl\/wp-content\/uploads\/2021\/03\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego.jpg\" alt=\"Junge trainiert in einem Fitnessstudio im Freien\" width=\"1110\" height=\"740\" srcset=\"https:\/\/freekids.pl\/wp-content\/uploads\/2021\/03\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego.jpg 1110w, https:\/\/freekids.pl\/wp-content\/uploads\/2021\/03\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego-800x533.jpg 800w, https:\/\/freekids.pl\/wp-content\/uploads\/2021\/03\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego-300x200.jpg 300w, https:\/\/freekids.pl\/wp-content\/uploads\/2021\/03\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego-1024x683.jpg 1024w, https:\/\/freekids.pl\/wp-content\/uploads\/2021\/03\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego-768x512.jpg 768w\" sizes=\"auto, (max-width: 1110px) 100vw, 1110px\" \/>\n        <\/p>\n<p style=\"text-align: justify;\">\n  Es ist eine bekannte Tatsache, dass Bewegung gut f\u00fcr Sie ist. Aus diesem Grund ist der Sportunterricht in der Schule von gro\u00dfer Bedeutung, weil er gute Gewohnheiten f\u00fcr die Zukunft pr\u00e4gen kann. Damit die Sch\u00fcler jedoch bereitwillig am Unterricht teilnehmen, muss dieser so attraktiv wie m\u00f6glich sein. Leider verf\u00fcgen die Schulen oft nicht \u00fcber die entsprechenden Einrichtungen, was dazu f\u00fchrt, dass die Sch\u00fcler z\u00f6gern und sich nicht bewegen wollen. Fitnessstudios im Freien k\u00f6nnen hier Abhilfe schaffen, und Outdoor-Fitness ist eine hervorragende M\u00f6glichkeit, den Sportunterricht abwechslungsreich zu gestalten.\n        <\/p>\n<p style=\"text-align: justify;\">\n  \u00dcberf\u00fcllte Turnhallen und Zweikampfspiele sind im Sportunterricht immer seltener anzutreffen. Immer mehr Lehrer sind sich bewusst, dass der Unterricht attraktiv und abwechslungsreich sein sollte, und suchen daher nach alternativen M\u00f6glichkeiten, ihn durchzuf\u00fchren. Eine hervorragende M\u00f6glichkeit dazu ist <strong>Street Workout oder \u00dcbungen im Freien<\/strong>, die in <a href=\"https:\/\/freekids.pl\/produkty\/street-workout\/\">Turnhallen<\/a> durchgef\u00fchrt werden. Dies sind Orte, die mit einer Vielzahl von Ger\u00e4ten ausgestattet sind, so dass sie sowohl Herz-Kreislauf-Aktivit\u00e4ten als auch Krafttraining erm\u00f6glichen. Die Art der Aktivit\u00e4t kann daher leicht auf das Alter und die Bed\u00fcrfnisse der Sch\u00fcler zugeschnitten werden, um ihre motorischen F\u00e4higkeiten optimal zu entwickeln.\n        <\/p>\n<p style=\"text-align: justify;\">\n  Diese Art von Training hat au\u00dferdem den unglaublichen Vorteil, dass es im Freien stattfindet. Die Vorteile von Sport im Freien sind von unsch\u00e4tzbarem Wert und haben viel mehr Vorteile als die in geschlossenen R\u00e4umen. In erster Linie wird <strong>der K\u00f6rper mit Sauerstoff versorgt<\/strong>, was zu einer besseren Konzentration f\u00fchrt und sich positiv auf die Gehirnfunktion auswirkt. Dies ist besonders wichtig f\u00fcr Kinder und Jugendliche. Nach einer Sportstunde im Freien arbeiten die Sch\u00fcler in den folgenden Schulstunden viel effektiver.\n        <\/p>\n<p style=\"text-align: justify;\">\n  Dar\u00fcber hinaus verbessert regelm\u00e4\u00dfiges Training den Stoffwechsel und <strong>verbrennt schneller Fett<\/strong>. Es ist daher eine ausgezeichnete Wahl f\u00fcr junge Menschen, die viel Zeit vor dem Computer verbringen und sich meist ungesund ern\u00e4hren. Bewegung im Freien liefert an sonnigen Tagen eine wichtige Dosis Vitamin D, was sich in ges\u00fcnderen und st\u00e4rkeren Knochen niederschl\u00e4gt. An kalten Tagen hingegen macht das Training an den Street-Workout-Ger\u00e4ten einen jungen Menschen h\u00e4rter, wodurch er viel weniger anf\u00e4llig f\u00fcr Infektionen ist und sich in Zukunft leichter dagegen wehren kann.\n        <\/p>\n<p style=\"text-align: justify;\">\n  Fitness im Freien ist eine hervorragende Erg\u00e4nzung des Sportunterrichts, die nicht nur f\u00fcr die Sch\u00fcler attraktiv ist, sondern auch viele gesundheitliche Vorteile hat.\n        <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Es ist eine bekannte Tatsache, dass Bewegung gut f\u00fcr Sie ist. Aus diesem Grund ist der Sportunterricht in der Schule von gro\u00dfer Bedeutung, weil er gute Gewohnheiten f\u00fcr die Zukunft pr\u00e4gen kann. Damit die Sch\u00fcler jedoch bereitwillig am Unterricht teilnehmen, muss dieser so attraktiv wie m\u00f6glich sein. Leider verf\u00fcgen die Schulen oft nicht \u00fcber die entsprechenden Einrichtungen, was dazu f\u00fchrt, dass die Sch\u00fcler z\u00f6gern und sich nicht bewegen wollen. Fitnessstudios im Freien k\u00f6nnen hier Abhilfe schaffen, und Outdoor-Fitness ist eine hervorragende M\u00f6glichkeit, den Sportunterricht abwechslungsreich zu gestalten.      <\/p>\n","protected":false},"author":2,"featured_media":66098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[871],"tags":[],"class_list":["post-199430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fitness im Freien als Bereicherung des Sportunterrichts - Freekids.pl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fitness im Freien als Bereicherung des Sportunterrichts - Freekids.pl\" \/>\n<meta property=\"og:description\" content=\"Es ist eine bekannte Tatsache, dass Bewegung gut f\u00fcr Sie ist. Aus diesem Grund ist der Sportunterricht in der Schule von gro\u00dfer Bedeutung, weil er gute Gewohnheiten f\u00fcr die Zukunft pr\u00e4gen kann. Damit die Sch\u00fcler jedoch bereitwillig am Unterricht teilnehmen, muss dieser so attraktiv wie m\u00f6glich sein. Leider verf\u00fcgen die Schulen oft nicht \u00fcber die entsprechenden Einrichtungen, was dazu f\u00fchrt, dass die Sch\u00fcler z\u00f6gern und sich nicht bewegen wollen. Fitnessstudios im Freien k\u00f6nnen hier Abhilfe schaffen, und Outdoor-Fitness ist eine hervorragende M\u00f6glichkeit, den Sportunterricht abwechslungsreich zu gestalten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/\" \/>\n<meta property=\"og:site_name\" content=\"FreeKids Playgrounds | Sport | Urban Furniture\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-01T13:05:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/freekids.pl\/wp-content\/uploads\/2021\/03\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1110\" \/>\n\t<meta property=\"og:image:height\" content=\"740\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"freekids_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"freekids_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/fitness-im-freien-als-bereicherung-des-sportunterrichts\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/fitness-im-freien-als-bereicherung-des-sportunterrichts\\\/\"},\"author\":{\"name\":\"freekids_admin\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/#\\\/schema\\\/person\\\/8cc285d5df0596acbe794b879927e6cc\"},\"headline\":\"Fitness im Freien als Bereicherung des Sportunterrichts\",\"datePublished\":\"2021-03-01T13:05:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/fitness-im-freien-als-bereicherung-des-sportunterrichts\\\/\"},\"wordCount\":414,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/fitness-im-freien-als-bereicherung-des-sportunterrichts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/freekids.pl\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/freekids.pl\\\/de\\\/fitness-im-freien-als-bereicherung-des-sportunterrichts\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/fitness-im-freien-als-bereicherung-des-sportunterrichts\\\/\",\"url\":\"https:\\\/\\\/freekids.pl\\\/de\\\/fitness-im-freien-als-bereicherung-des-sportunterrichts\\\/\",\"name\":\"Fitness im Freien als Bereicherung des Sportunterrichts - Freekids.pl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/fitness-im-freien-als-bereicherung-des-sportunterrichts\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/fitness-im-freien-als-bereicherung-des-sportunterrichts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/freekids.pl\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego.jpg\",\"datePublished\":\"2021-03-01T13:05:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/#\\\/schema\\\/person\\\/8cc285d5df0596acbe794b879927e6cc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/fitness-im-freien-als-bereicherung-des-sportunterrichts\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/freekids.pl\\\/de\\\/fitness-im-freien-als-bereicherung-des-sportunterrichts\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/fitness-im-freien-als-bereicherung-des-sportunterrichts\\\/#primaryimage\",\"url\":\"https:\\\/\\\/freekids.pl\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego.jpg\",\"contentUrl\":\"https:\\\/\\\/freekids.pl\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego.jpg\",\"width\":1110,\"height\":740},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/fitness-im-freien-als-bereicherung-des-sportunterrichts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/freekids.pl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fitness im Freien als Bereicherung des Sportunterrichts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/freekids.pl\\\/de\\\/\",\"name\":\"FreeKids Playgrounds | Sport | Urban Furniture\",\"description\":\"Dream it, do it !\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/freekids.pl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/#\\\/schema\\\/person\\\/8cc285d5df0596acbe794b879927e6cc\",\"name\":\"freekids_admin\",\"url\":\"https:\\\/\\\/freekids.pl\\\/de\\\/author\\\/freekids_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fitness im Freien als Bereicherung des Sportunterrichts - Freekids.pl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/","og_locale":"de_DE","og_type":"article","og_title":"Fitness im Freien als Bereicherung des Sportunterrichts - Freekids.pl","og_description":"Es ist eine bekannte Tatsache, dass Bewegung gut f\u00fcr Sie ist. Aus diesem Grund ist der Sportunterricht in der Schule von gro\u00dfer Bedeutung, weil er gute Gewohnheiten f\u00fcr die Zukunft pr\u00e4gen kann. Damit die Sch\u00fcler jedoch bereitwillig am Unterricht teilnehmen, muss dieser so attraktiv wie m\u00f6glich sein. Leider verf\u00fcgen die Schulen oft nicht \u00fcber die entsprechenden Einrichtungen, was dazu f\u00fchrt, dass die Sch\u00fcler z\u00f6gern und sich nicht bewegen wollen. Fitnessstudios im Freien k\u00f6nnen hier Abhilfe schaffen, und Outdoor-Fitness ist eine hervorragende M\u00f6glichkeit, den Sportunterricht abwechslungsreich zu gestalten.","og_url":"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/","og_site_name":"FreeKids Playgrounds | Sport | Urban Furniture","article_published_time":"2021-03-01T13:05:09+00:00","og_image":[{"width":1110,"height":740,"url":"https:\/\/freekids.pl\/wp-content\/uploads\/2021\/03\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego.jpg","type":"image\/jpeg"}],"author":"freekids_admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"freekids_admin","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/#article","isPartOf":{"@id":"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/"},"author":{"name":"freekids_admin","@id":"https:\/\/freekids.pl\/de\/#\/schema\/person\/8cc285d5df0596acbe794b879927e6cc"},"headline":"Fitness im Freien als Bereicherung des Sportunterrichts","datePublished":"2021-03-01T13:05:09+00:00","mainEntityOfPage":{"@id":"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/"},"wordCount":414,"commentCount":0,"image":{"@id":"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/#primaryimage"},"thumbnailUrl":"https:\/\/freekids.pl\/wp-content\/uploads\/2021\/03\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego.jpg","articleSection":["Blog"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/","url":"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/","name":"Fitness im Freien als Bereicherung des Sportunterrichts - Freekids.pl","isPartOf":{"@id":"https:\/\/freekids.pl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/#primaryimage"},"image":{"@id":"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/#primaryimage"},"thumbnailUrl":"https:\/\/freekids.pl\/wp-content\/uploads\/2021\/03\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego.jpg","datePublished":"2021-03-01T13:05:09+00:00","author":{"@id":"https:\/\/freekids.pl\/de\/#\/schema\/person\/8cc285d5df0596acbe794b879927e6cc"},"breadcrumb":{"@id":"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/#primaryimage","url":"https:\/\/freekids.pl\/wp-content\/uploads\/2021\/03\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego.jpg","contentUrl":"https:\/\/freekids.pl\/wp-content\/uploads\/2021\/03\/outdoor-fitness-jako-urozmaicenie-lekcji-wychowania-fizycznego.jpg","width":1110,"height":740},{"@type":"BreadcrumbList","@id":"https:\/\/freekids.pl\/de\/fitness-im-freien-als-bereicherung-des-sportunterrichts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/freekids.pl\/de\/"},{"@type":"ListItem","position":2,"name":"Fitness im Freien als Bereicherung des Sportunterrichts"}]},{"@type":"WebSite","@id":"https:\/\/freekids.pl\/de\/#website","url":"https:\/\/freekids.pl\/de\/","name":"FreeKids Playgrounds | Sport | Urban Furniture","description":"Dream it, do it !","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/freekids.pl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/freekids.pl\/de\/#\/schema\/person\/8cc285d5df0596acbe794b879927e6cc","name":"freekids_admin","url":"https:\/\/freekids.pl\/de\/author\/freekids_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/posts\/199430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/comments?post=199430"}],"version-history":[{"count":0,"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/posts\/199430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/media\/66098"}],"wp:attachment":[{"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/media?parent=199430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/categories?post=199430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/tags?post=199430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}