{"id":200592,"date":"2024-10-24T03:05:24","date_gmt":"2024-10-24T01:05:24","guid":{"rendered":"https:\/\/freekids.pl\/produkt\/tunnel-unter-dem-huegel\/"},"modified":"2024-10-24T03:05:24","modified_gmt":"2024-10-24T01:05:24","slug":"tunnel-unter-dem-huegel","status":"publish","type":"product","link":"https:\/\/freekids.pl\/de\/produkt\/tunnel-unter-dem-huegel\/","title":{"rendered":"Tunnel unter dem H\u00fcgel"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":176642,"template":"","meta":{"_acf_changed":false,"ep_exclude_from_search":false},"product_brand":[],"product_cat":[517,537,477],"product_tag":[],"class_list":["post-200592","product","type-product","status-publish","has-post-thumbnail","product_cat-am-hang","product_cat-hindernisparcours","product_cat-spielplatze","first","outofstock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tunnel unter dem H\u00fcgel - Freekids.pl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/freekids.pl\/de\/produkt\/tunnel-unter-dem-huegel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tunnel unter dem H\u00fcgel - Freekids.pl\" \/>\n<meta property=\"og:url\" content=\"https:\/\/freekids.pl\/de\/produkt\/tunnel-unter-dem-huegel\/\" \/>\n<meta property=\"og:site_name\" content=\"FreeKids Playgrounds | Sport | Urban Furniture\" \/>\n<meta property=\"og:image\" content=\"https:\/\/freekids.pl\/wp-content\/uploads\/2025\/01\/0280119_tunel_pod_gorka_-_wiz.1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1353\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/produkt\\\/tunnel-unter-dem-huegel\\\/\",\"url\":\"https:\\\/\\\/freekids.pl\\\/de\\\/produkt\\\/tunnel-unter-dem-huegel\\\/\",\"name\":\"Tunnel unter dem H\u00fcgel - Freekids.pl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/produkt\\\/tunnel-unter-dem-huegel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/produkt\\\/tunnel-unter-dem-huegel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/freekids.pl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/0280119_tunel_pod_gorka_-_wiz.1-scaled.jpg\",\"datePublished\":\"2024-10-24T01:05:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/produkt\\\/tunnel-unter-dem-huegel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/freekids.pl\\\/de\\\/produkt\\\/tunnel-unter-dem-huegel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/produkt\\\/tunnel-unter-dem-huegel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/freekids.pl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/0280119_tunel_pod_gorka_-_wiz.1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/freekids.pl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/0280119_tunel_pod_gorka_-_wiz.1-scaled.jpg\",\"width\":2560,\"height\":1353},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/produkt\\\/tunnel-unter-dem-huegel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/freekids.pl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/freekids.pl\\\/de\\\/produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tunnel unter dem H\u00fcgel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/freekids.pl\\\/de\\\/\",\"name\":\"FreeKids Playgrounds | Sport | Urban Furniture\",\"description\":\"Dream it, do it !\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/freekids.pl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tunnel unter dem H\u00fcgel - Freekids.pl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/freekids.pl\/de\/produkt\/tunnel-unter-dem-huegel\/","og_locale":"de_DE","og_type":"article","og_title":"Tunnel unter dem H\u00fcgel - Freekids.pl","og_url":"https:\/\/freekids.pl\/de\/produkt\/tunnel-unter-dem-huegel\/","og_site_name":"FreeKids Playgrounds | Sport | Urban Furniture","og_image":[{"width":2560,"height":1353,"url":"https:\/\/freekids.pl\/wp-content\/uploads\/2025\/01\/0280119_tunel_pod_gorka_-_wiz.1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/freekids.pl\/de\/produkt\/tunnel-unter-dem-huegel\/","url":"https:\/\/freekids.pl\/de\/produkt\/tunnel-unter-dem-huegel\/","name":"Tunnel unter dem H\u00fcgel - Freekids.pl","isPartOf":{"@id":"https:\/\/freekids.pl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/freekids.pl\/de\/produkt\/tunnel-unter-dem-huegel\/#primaryimage"},"image":{"@id":"https:\/\/freekids.pl\/de\/produkt\/tunnel-unter-dem-huegel\/#primaryimage"},"thumbnailUrl":"https:\/\/freekids.pl\/wp-content\/uploads\/2025\/01\/0280119_tunel_pod_gorka_-_wiz.1-scaled.jpg","datePublished":"2024-10-24T01:05:24+00:00","breadcrumb":{"@id":"https:\/\/freekids.pl\/de\/produkt\/tunnel-unter-dem-huegel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/freekids.pl\/de\/produkt\/tunnel-unter-dem-huegel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/freekids.pl\/de\/produkt\/tunnel-unter-dem-huegel\/#primaryimage","url":"https:\/\/freekids.pl\/wp-content\/uploads\/2025\/01\/0280119_tunel_pod_gorka_-_wiz.1-scaled.jpg","contentUrl":"https:\/\/freekids.pl\/wp-content\/uploads\/2025\/01\/0280119_tunel_pod_gorka_-_wiz.1-scaled.jpg","width":2560,"height":1353},{"@type":"BreadcrumbList","@id":"https:\/\/freekids.pl\/de\/produkt\/tunnel-unter-dem-huegel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/freekids.pl\/de\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/freekids.pl\/de\/produkte\/"},{"@type":"ListItem","position":3,"name":"Tunnel unter dem H\u00fcgel"}]},{"@type":"WebSite","@id":"https:\/\/freekids.pl\/de\/#website","url":"https:\/\/freekids.pl\/de\/","name":"FreeKids Playgrounds | Sport | Urban Furniture","description":"Dream it, do it !","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/freekids.pl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/product\/200592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/media\/176642"}],"wp:attachment":[{"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/media?parent=200592"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/product_brand?post=200592"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/product_cat?post=200592"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/freekids.pl\/de\/wp-json\/wp\/v2\/product_tag?post=200592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}