{"id":199505,"date":"2020-11-03T15:15:35","date_gmt":"2020-11-03T14:15:35","guid":{"rendered":"https:\/\/freekids.pl\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/"},"modified":"2020-11-03T15:15:35","modified_gmt":"2020-11-03T14:15:35","slug":"como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre","status":"publish","type":"post","link":"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/","title":{"rendered":"\u00bfC\u00f3mo se utiliza una m\u00e1quina de remo en un gimnasio al aire libre?"},"content":{"rendered":"<div class=\"section standard\">\n<div class=\"row\">\n<div class=\"column\" style=\"width: 100%;\">\n<div class=\"content\">\n<p style=\"text-align: center;\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9365\" src=\"https:\/\/freekids.pl\/wp-content\/uploads\/2020\/11\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej.jpg\" alt=\"\" width=\"1110\" height=\"740\" srcset=\"https:\/\/freekids.pl\/wp-content\/uploads\/2020\/11\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej.jpg 1110w, https:\/\/freekids.pl\/wp-content\/uploads\/2020\/11\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej-800x533.jpg 800w, https:\/\/freekids.pl\/wp-content\/uploads\/2020\/11\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej-300x200.jpg 300w, https:\/\/freekids.pl\/wp-content\/uploads\/2020\/11\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej-1024x683.jpg 1024w, https:\/\/freekids.pl\/wp-content\/uploads\/2020\/11\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej-768x512.jpg 768w\" sizes=\"auto, (max-width: 1110px) 100vw, 1110px\" \/>\n        <\/p>\n<p>\n  El erg\u00f3metro de remo es una m\u00e1quina que reproduce perfectamente el remo real sobre el agua. Esta m\u00e1quina se utilizaba ya en la d\u00e9cada de 1950, principalmente para el entrenamiento profesional de remeros. Sin embargo, las numerosas ventajas de hacer ejercicio en un erg\u00f3metro hicieron que el aparato se popularizara r\u00e1pidamente entre el p\u00fablico en general. Hoy en d\u00eda, la llamada m\u00e1quina de remo se puede encontrar en muchos gimnasios, tanto tradicionales como al aire libre.\n        <\/p>\n<p>\n  El ejercicio en un erg\u00f3metro de remo compromete <strong>la mayor parte de los m\u00fasculos<\/strong>, incluidos los brazos, las piernas, el abdomen, la espalda, los gl\u00fateos y el pecho. Es un tipo de entrenamiento aer\u00f3bico (cardio) que mejora la eficiencia del cuerpo, fortalece los m\u00fasculos, esculpe toda la silueta y tambi\u00e9n ayuda a deshacerse de los kilos de m\u00e1s con relativa rapidez. Esto se debe a que hacer ejercicio en una m\u00e1quina de remo te permite <strong>quemar m\u00e1s calor\u00edas<\/strong> que durante otros ejercicios cardiovasculares populares, como montar en bicicleta, nadar o correr. Adem\u00e1s, este entrenamiento no somete a tensi\u00f3n a las articulaciones y puede utilizarse como calentamiento ideal. Sin embargo, para disfrutar de todos estos beneficios, es <strong>importante<\/strong> recordar algunas <strong>reglas importantes para<\/strong> utilizar el simulador de remo.\n        <\/p>\n<h2><strong>Fundamentos del ejercicio de remo<\/strong><\/h2>\n<p>\n  Antes de empezar a entrenar en <a href=\"https:\/\/freekids.pl\/produkty\/street-workout\/\">un gimnasio al aire libre<\/a>, familiar\u00edzate con la informaci\u00f3n m\u00e1s importante sobre c\u00f3mo utilizar el equipo que m\u00e1s te interese. Esto te ayudar\u00e1 a reducir el riesgo de lesiones y a obtener buenos resultados. \u00bfC\u00f3mo se hace ejercicio con una m\u00e1quina de remo?\n        <\/p>\n<p>\n  Sobre todo, recuerda que <strong>la fuerza debe centrarse en el trabajo de piernas<\/strong>. La posici\u00f3n inicial tambi\u00e9n es muy importante. Si\u00e9ntate en el sill\u00edn, dobla las piernas por las rodillas y coloca los pies en soportes especiales. Ag\u00e1rrate a las barandillas e incl\u00ednate ligeramente hacia delante para que tus brazos est\u00e9n rectos pero no muy tensos. Tu espalda debe estar recta.\n        <\/p>\n<p>\n  Ahora puedes pasar a la segunda fase, el tir\u00f3n. Empieza a enderezar <g id=\"gid_0\">ambas piernas al mismo tiempo<\/g> con un movimiento suave y fluido, y deja los brazos en la misma posici\u00f3n. Cuando las piernas est\u00e9n completamente estiradas, tira de las asas hacia ti doblando los brazos por los antebrazos: deben quedar perpendiculares al suelo.\n        <\/p>\n<p>\n  Una a una, d\u00f3blate ligeramente, alejando las barras de ti. Cuando est\u00e9n por encima de tus rodillas, flexiona lentamente las piernas, volviendo a la posici\u00f3n inicial. <strong>Recuerda que no debes doblar las mu\u00f1ecas, ni tampoco la espalda<\/strong>, ya que la sobrecargar\u00edas. Adem\u00e1s, no hagas ejercicios largos y frecuentes si eres principiante. Aumenta gradualmente la intensidad, la duraci\u00f3n y las repeticiones de tus ejercicios y los resultados llegar\u00e1n antes de lo que esperas. Tus primeros ejercicios en la m\u00e1quina de remo deben durar unos 15 minutos, realizados dos veces por semana.\n        <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El erg\u00f3metro de remo es una m\u00e1quina que reproduce perfectamente el remo real sobre el agua. Esta m\u00e1quina se utilizaba ya en la d\u00e9cada de 1950, principalmente para el entrenamiento profesional de remeros. Sin embargo, las numerosas ventajas de hacer ejercicio en un erg\u00f3metro hicieron que el aparato se popularizara r\u00e1pidamente entre el p\u00fablico en general. Hoy en d\u00eda, la llamada m\u00e1quina de remo se puede encontrar en muchos gimnasios, tanto tradicionales como al aire libre.     <\/p>\n","protected":false},"author":2,"featured_media":58446,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[870],"tags":[],"class_list":["post-199505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las reglas m\u00e1s importantes para utilizar un erg\u00f3metro de remo<\/title>\n<meta name=\"description\" content=\"Antes de empezar a entrenar en un gimnasio al aire libre, familiar\u00edzate con el uso de los distintos aparatos. En este art\u00edculo hablaremos de la popular m\u00e1quina de remo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las reglas m\u00e1s importantes para utilizar un erg\u00f3metro de remo\" \/>\n<meta property=\"og:description\" content=\"Antes de empezar a entrenar en un gimnasio al aire libre, familiar\u00edzate con el uso de los distintos aparatos. En este art\u00edculo hablaremos de la popular m\u00e1quina de remo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/\" \/>\n<meta property=\"og:site_name\" content=\"FreeKids Playgrounds | Sport | Urban Furniture\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-03T14:15:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/freekids.pl\/wp-content\/uploads\/2020\/11\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1110\" \/>\n\t<meta property=\"og:image:height\" content=\"740\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"freekids_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"freekids_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\\\/\"},\"author\":{\"name\":\"freekids_admin\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/#\\\/schema\\\/person\\\/8cc285d5df0596acbe794b879927e6cc\"},\"headline\":\"\u00bfC\u00f3mo se utiliza una m\u00e1quina de remo en un gimnasio al aire libre?\",\"datePublished\":\"2020-11-03T14:15:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\\\/\"},\"wordCount\":522,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/freekids.pl\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/freekids.pl\\\/es\\\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\\\/\",\"url\":\"https:\\\/\\\/freekids.pl\\\/es\\\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\\\/\",\"name\":\"Las reglas m\u00e1s importantes para utilizar un erg\u00f3metro de remo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/freekids.pl\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej.jpg\",\"datePublished\":\"2020-11-03T14:15:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/#\\\/schema\\\/person\\\/8cc285d5df0596acbe794b879927e6cc\"},\"description\":\"Antes de empezar a entrenar en un gimnasio al aire libre, familiar\u00edzate con el uso de los distintos aparatos. En este art\u00edculo hablaremos de la popular m\u00e1quina de remo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/freekids.pl\\\/es\\\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/freekids.pl\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej.jpg\",\"contentUrl\":\"https:\\\/\\\/freekids.pl\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej.jpg\",\"width\":1110,\"height\":740},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/freekids.pl\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo se utiliza una m\u00e1quina de remo en un gimnasio al aire libre?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/freekids.pl\\\/es\\\/\",\"name\":\"FreeKids Playgrounds | Sport | Urban Furniture\",\"description\":\"Dream it, do it !\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/freekids.pl\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/#\\\/schema\\\/person\\\/8cc285d5df0596acbe794b879927e6cc\",\"name\":\"freekids_admin\",\"url\":\"https:\\\/\\\/freekids.pl\\\/es\\\/author\\\/freekids_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las reglas m\u00e1s importantes para utilizar un erg\u00f3metro de remo","description":"Antes de empezar a entrenar en un gimnasio al aire libre, familiar\u00edzate con el uso de los distintos aparatos. En este art\u00edculo hablaremos de la popular m\u00e1quina de remo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/","og_locale":"es_ES","og_type":"article","og_title":"Las reglas m\u00e1s importantes para utilizar un erg\u00f3metro de remo","og_description":"Antes de empezar a entrenar en un gimnasio al aire libre, familiar\u00edzate con el uso de los distintos aparatos. En este art\u00edculo hablaremos de la popular m\u00e1quina de remo.","og_url":"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/","og_site_name":"FreeKids Playgrounds | Sport | Urban Furniture","article_published_time":"2020-11-03T14:15:35+00:00","og_image":[{"width":1110,"height":740,"url":"https:\/\/freekids.pl\/wp-content\/uploads\/2020\/11\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej.jpg","type":"image\/jpeg"}],"author":"freekids_admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"freekids_admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/#article","isPartOf":{"@id":"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/"},"author":{"name":"freekids_admin","@id":"https:\/\/freekids.pl\/es\/#\/schema\/person\/8cc285d5df0596acbe794b879927e6cc"},"headline":"\u00bfC\u00f3mo se utiliza una m\u00e1quina de remo en un gimnasio al aire libre?","datePublished":"2020-11-03T14:15:35+00:00","mainEntityOfPage":{"@id":"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/"},"wordCount":522,"commentCount":0,"image":{"@id":"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/#primaryimage"},"thumbnailUrl":"https:\/\/freekids.pl\/wp-content\/uploads\/2020\/11\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej.jpg","articleSection":["Blog"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/","url":"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/","name":"Las reglas m\u00e1s importantes para utilizar un erg\u00f3metro de remo","isPartOf":{"@id":"https:\/\/freekids.pl\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/#primaryimage"},"image":{"@id":"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/#primaryimage"},"thumbnailUrl":"https:\/\/freekids.pl\/wp-content\/uploads\/2020\/11\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej.jpg","datePublished":"2020-11-03T14:15:35+00:00","author":{"@id":"https:\/\/freekids.pl\/es\/#\/schema\/person\/8cc285d5df0596acbe794b879927e6cc"},"description":"Antes de empezar a entrenar en un gimnasio al aire libre, familiar\u00edzate con el uso de los distintos aparatos. En este art\u00edculo hablaremos de la popular m\u00e1quina de remo.","breadcrumb":{"@id":"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/#primaryimage","url":"https:\/\/freekids.pl\/wp-content\/uploads\/2020\/11\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej.jpg","contentUrl":"https:\/\/freekids.pl\/wp-content\/uploads\/2020\/11\/jak-korzystac-z-wioslarza-na-silowni-zewnetrznej.jpg","width":1110,"height":740},{"@type":"BreadcrumbList","@id":"https:\/\/freekids.pl\/es\/como-se-utiliza-una-maquina-de-remo-en-un-gimnasio-al-aire-libre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/freekids.pl\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo se utiliza una m\u00e1quina de remo en un gimnasio al aire libre?"}]},{"@type":"WebSite","@id":"https:\/\/freekids.pl\/es\/#website","url":"https:\/\/freekids.pl\/es\/","name":"FreeKids Playgrounds | Sport | Urban Furniture","description":"Dream it, do it !","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/freekids.pl\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/freekids.pl\/es\/#\/schema\/person\/8cc285d5df0596acbe794b879927e6cc","name":"freekids_admin","url":"https:\/\/freekids.pl\/es\/author\/freekids_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/posts\/199505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/comments?post=199505"}],"version-history":[{"count":0,"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/posts\/199505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/media\/58446"}],"wp:attachment":[{"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/media?parent=199505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/categories?post=199505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/tags?post=199505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}