{"id":200722,"date":"2024-10-24T02:42:03","date_gmt":"2024-10-24T00:42:03","guid":{"rendered":"https:\/\/freekids.pl\/produkt\/arenas-movedizas-4\/"},"modified":"2024-10-24T02:42:03","modified_gmt":"2024-10-24T00:42:03","slug":"arenas-movedizas-4","status":"publish","type":"product","link":"https:\/\/freekids.pl\/es\/produkt\/arenas-movedizas-4\/","title":{"rendered":"Arenas movedizas 4"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>El dispositivo se basa en postes redondos de acero. Cubos de goma, toboganes de tubos de acero inoxidable. Las tapas se apoyan en un marco soldado hecho de perfiles de acero. Los postes est\u00e1n acabados con tapas de goma esf\u00e9ricas.   <\/p>\n<div id=\"highlighter--hover-tools\" style=\"display: none;\">\n<div id=\"highlighter--hover-tools--container\">\n<div class=\"highlighter--icon highlighter--icon-copy\" title=\"Copia\"><\/div>\n<div class=\"highlighter--icon highlighter--icon-change-color\" title=\"Cambiar color\"><\/div>\n<div class=\"highlighter--icon highlighter--icon-delete\" title=\"Borra\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":181693,"template":"","meta":{"_acf_changed":false,"ep_exclude_from_search":false},"product_brand":[],"product_cat":[523,478],"product_tag":[],"class_list":["post-200722","product","type-product","status-publish","has-post-thumbnail","product_series-quicksand-es","product_group-metal-es","product_cat-areneros-y-accesorios","product_cat-parques-infantiles","first","outofstock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arenas movedizas 4 - Freekids.pl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/freekids.pl\/es\/produkt\/arenas-movedizas-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arenas movedizas 4 - Freekids.pl\" \/>\n<meta property=\"og:description\" content=\"El dispositivo se basa en postes redondos de acero. Cubos de goma, toboganes de tubos de acero inoxidable. Las tapas se apoyan en un marco soldado hecho de perfiles de acero. Los postes est\u00e1n acabados con tapas de goma esf\u00e9ricas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/freekids.pl\/es\/produkt\/arenas-movedizas-4\/\" \/>\n<meta property=\"og:site_name\" content=\"FreeKids Playgrounds | Sport | Urban Furniture\" \/>\n<meta property=\"og:image\" content=\"https:\/\/freekids.pl\/wp-content\/uploads\/2025\/01\/0095021_ruchome_piaski_4_-_wiz.1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1604\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/produkt\\\/arenas-movedizas-4\\\/\",\"url\":\"https:\\\/\\\/freekids.pl\\\/es\\\/produkt\\\/arenas-movedizas-4\\\/\",\"name\":\"Arenas movedizas 4 - Freekids.pl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/produkt\\\/arenas-movedizas-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/produkt\\\/arenas-movedizas-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/freekids.pl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/0095021_ruchome_piaski_4_-_wiz.1.jpg\",\"datePublished\":\"2024-10-24T00:42:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/produkt\\\/arenas-movedizas-4\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/freekids.pl\\\/es\\\/produkt\\\/arenas-movedizas-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/produkt\\\/arenas-movedizas-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/freekids.pl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/0095021_ruchome_piaski_4_-_wiz.1.jpg\",\"contentUrl\":\"https:\\\/\\\/freekids.pl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/0095021_ruchome_piaski_4_-_wiz.1.jpg\",\"width\":1920,\"height\":1604},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/produkt\\\/arenas-movedizas-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/freekids.pl\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/freekids.pl\\\/es\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arenas movedizas 4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/freekids.pl\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/freekids.pl\\\/es\\\/\",\"name\":\"FreeKids Playgrounds | Sport | Urban Furniture\",\"description\":\"Dream it, do it !\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/freekids.pl\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arenas movedizas 4 - Freekids.pl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/freekids.pl\/es\/produkt\/arenas-movedizas-4\/","og_locale":"es_ES","og_type":"article","og_title":"Arenas movedizas 4 - Freekids.pl","og_description":"El dispositivo se basa en postes redondos de acero. Cubos de goma, toboganes de tubos de acero inoxidable. Las tapas se apoyan en un marco soldado hecho de perfiles de acero. Los postes est\u00e1n acabados con tapas de goma esf\u00e9ricas.","og_url":"https:\/\/freekids.pl\/es\/produkt\/arenas-movedizas-4\/","og_site_name":"FreeKids Playgrounds | Sport | Urban Furniture","og_image":[{"width":1920,"height":1604,"url":"https:\/\/freekids.pl\/wp-content\/uploads\/2025\/01\/0095021_ruchome_piaski_4_-_wiz.1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/freekids.pl\/es\/produkt\/arenas-movedizas-4\/","url":"https:\/\/freekids.pl\/es\/produkt\/arenas-movedizas-4\/","name":"Arenas movedizas 4 - Freekids.pl","isPartOf":{"@id":"https:\/\/freekids.pl\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/freekids.pl\/es\/produkt\/arenas-movedizas-4\/#primaryimage"},"image":{"@id":"https:\/\/freekids.pl\/es\/produkt\/arenas-movedizas-4\/#primaryimage"},"thumbnailUrl":"https:\/\/freekids.pl\/wp-content\/uploads\/2025\/01\/0095021_ruchome_piaski_4_-_wiz.1.jpg","datePublished":"2024-10-24T00:42:03+00:00","breadcrumb":{"@id":"https:\/\/freekids.pl\/es\/produkt\/arenas-movedizas-4\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/freekids.pl\/es\/produkt\/arenas-movedizas-4\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/freekids.pl\/es\/produkt\/arenas-movedizas-4\/#primaryimage","url":"https:\/\/freekids.pl\/wp-content\/uploads\/2025\/01\/0095021_ruchome_piaski_4_-_wiz.1.jpg","contentUrl":"https:\/\/freekids.pl\/wp-content\/uploads\/2025\/01\/0095021_ruchome_piaski_4_-_wiz.1.jpg","width":1920,"height":1604},{"@type":"BreadcrumbList","@id":"https:\/\/freekids.pl\/es\/produkt\/arenas-movedizas-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/freekids.pl\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/freekids.pl\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"Arenas movedizas 4"}]},{"@type":"WebSite","@id":"https:\/\/freekids.pl\/es\/#website","url":"https:\/\/freekids.pl\/es\/","name":"FreeKids Playgrounds | Sport | Urban Furniture","description":"Dream it, do it !","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/freekids.pl\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/product\/200722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/media\/181693"}],"wp:attachment":[{"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/media?parent=200722"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/product_brand?post=200722"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/product_cat?post=200722"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/freekids.pl\/es\/wp-json\/wp\/v2\/product_tag?post=200722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}